{"id":8693,"date":"2023-07-24T13:50:49","date_gmt":"2023-07-24T16:50:49","guid":{"rendered":"https:\/\/www.santamariadelosangeles.cl\/web\/?p=8693"},"modified":"2023-08-03T13:57:22","modified_gmt":"2023-08-03T16:57:22","slug":"nueva-superiora-general-y-consejo-general-de-la-congregacion-rfmsc","status":"publish","type":"post","link":"https:\/\/www.santamariadelosangeles.cl\/web\/2023\/07\/24\/nueva-superiora-general-y-consejo-general-de-la-congregacion-rfmsc\/","title":{"rendered":"Nueva Superiora General y Consejo General de la Congregaci\u00f3n RFMSC"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8693\" class=\"elementor elementor-8693\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f15905 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f15905\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8d6eeb0\" data-id=\"8d6eeb0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f31f0c6 elementor-widget elementor-widget-text-editor\" data-id=\"f31f0c6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Las Religiosas Franciscanas Misioneras del Sagrado coraz\u00f3n reunidas en el Cap\u00edtulo<br \/>General XXI en Roma, anuncian con alegr\u00eda la elecci\u00f3n de la Nueva Superiora General\u00a0<span style=\"color: var( --e-global-color-text ); font-weight: var(--bs-body-font-weight); text-align: var(--bs-body-text-align);\">Sor Marta Camerotto. As\u00ed como tambi\u00e9n anuncian con entusiamo la elecci\u00f3n del nuevo consejo general.<\/span><\/p><p style=\"text-align: left;\">Roxanna Gheza Pontarelli directora del Colegio y en representaci\u00f3n de la\u00a0 Comunidad Educativa desea darle las m\u00e1s sinceras y afectuosas felicitaciones por el nuevo cargo.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13fdf40 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13fdf40\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1cd973f\" data-id=\"1cd973f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa9dd6d elementor-widget elementor-widget-image\" data-id=\"aa9dd6d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"218\" height=\"300\" src=\"https:\/\/www.santamariadelosangeles.cl\/web\/wp-content\/uploads\/2023\/07\/IMG-20230722-WA0000-744x1024.jpg\" class=\"attachment-large size-large wp-image-8272\" alt=\"\" srcset=\"https:\/\/www.santamariadelosangeles.cl\/web\/wp-content\/uploads\/2023\/07\/IMG-20230722-WA0000-744x1024.jpg 744w, https:\/\/www.santamariadelosangeles.cl\/web\/wp-content\/uploads\/2023\/07\/IMG-20230722-WA0000-218x300.jpg 218w, https:\/\/www.santamariadelosangeles.cl\/web\/wp-content\/uploads\/2023\/07\/IMG-20230722-WA0000-768x1056.jpg 768w, https:\/\/www.santamariadelosangeles.cl\/web\/wp-content\/uploads\/2023\/07\/IMG-20230722-WA0000.jpg 1068w\" sizes=\"(max-width: 218px) 100vw, 218px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Las Religiosas Franciscanas Misioneras del Sagrado coraz\u00f3n reunidas en el Cap\u00edtulo General XXI en Roma, anuncian con alegr\u00eda la elecci\u00f3n de la Nueva Superiora General\u00a0Sor Marta Camerotto. As\u00ed como tambi\u00e9n anuncian con entusiamo la elecci\u00f3n del nuevo consejo general. Roxanna Gheza Pontarelli directora del Colegio y en representaci\u00f3n de la\u00a0 Comunidad Educativa desea darle las [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8266,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-8693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-direccion"],"_links":{"self":[{"href":"https:\/\/www.santamariadelosangeles.cl\/web\/wp-json\/wp\/v2\/posts\/8693"}],"collection":[{"href":"https:\/\/www.santamariadelosangeles.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santamariadelosangeles.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santamariadelosangeles.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santamariadelosangeles.cl\/web\/wp-json\/wp\/v2\/comments?post=8693"}],"version-history":[{"count":7,"href":"https:\/\/www.santamariadelosangeles.cl\/web\/wp-json\/wp\/v2\/posts\/8693\/revisions"}],"predecessor-version":[{"id":8700,"href":"https:\/\/www.santamariadelosangeles.cl\/web\/wp-json\/wp\/v2\/posts\/8693\/revisions\/8700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santamariadelosangeles.cl\/web\/wp-json\/wp\/v2\/media\/8266"}],"wp:attachment":[{"href":"https:\/\/www.santamariadelosangeles.cl\/web\/wp-json\/wp\/v2\/media?parent=8693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santamariadelosangeles.cl\/web\/wp-json\/wp\/v2\/categories?post=8693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santamariadelosangeles.cl\/web\/wp-json\/wp\/v2\/tags?post=8693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}